{"id":13,"count":10,"description":"","link":"https:\/\/emcher.com\/emchioi\/category\/gaming\/","name":"Gaming","slug":"gaming","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/emcher.com\/emchioi\/wp-json\/wp\/v2\/categories\/13","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/emcher.com\/emchioi\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/emcher.com\/emchioi\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/emcher.com\/emchioi\/wp-json\/wp\/v2\/posts?categories=13"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}